{"id":8717,"date":"2026-01-17T17:27:26","date_gmt":"2026-01-17T17:27:26","guid":{"rendered":"https:\/\/www.punkgrossos.com\/?p=8717"},"modified":"2026-01-17T17:27:26","modified_gmt":"2026-01-17T17:27:26","slug":"historias-del-punk","status":"publish","type":"post","link":"https:\/\/www.punkgrossos.com\/index.php\/2026\/01\/17\/historias-del-punk\/","title":{"rendered":"Historias del Punk"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Que sorpresa e ilusi\u00f3n llegar a la p\u00e1gina 85 y encontrar nuestro logo en el c\u00f3mic Historias del Punk, de los grandes Carlos Azagra y Encarna Revuelta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un c\u00f3mic donde Pedro Pico y Pico Vena dan un repaso a la historia del Punk, los inicios, los primeros conciertos, los discos, los casetes y muchos, muchos grupos de la escena Punk.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Punk not Dead, Punk not Edad!!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.punkgrossos.com\/wp-content\/uploads\/2026\/01\/HPG-1-1-768x1024.jpg\" alt=\"\" class=\"wp-image-8719\" srcset=\"https:\/\/www.punkgrossos.com\/wp-content\/uploads\/2026\/01\/HPG-1-1-768x1024.jpg 768w, https:\/\/www.punkgrossos.com\/wp-content\/uploads\/2026\/01\/HPG-1-1-225x300.jpg 225w, https:\/\/www.punkgrossos.com\/wp-content\/uploads\/2026\/01\/HPG-1-1-1152x1536.jpg 1152w, https:\/\/www.punkgrossos.com\/wp-content\/uploads\/2026\/01\/HPG-1-1-1536x2048.jpg 1536w, https:\/\/www.punkgrossos.com\/wp-content\/uploads\/2026\/01\/HPG-1-1-scaled.jpg 1920w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Que sorpresa e ilusi\u00f3n llegar a la p\u00e1gina 85 y encontrar nuestro logo en el c\u00f3mic Historias del Punk, de los grandes Carlos Azagra y Encarna Revuelta. Un c\u00f3mic donde Pedro Pico y Pico Vena dan un repaso a la historia del Punk, los inicios, los primeros conciertos, los discos, los casetes y muchos, muchos &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.punkgrossos.com\/index.php\/2026\/01\/17\/historias-del-punk\/\" class=\"more-link\">Continua llegint <span class=\"screen-reader-text\">\u00abHistorias del Punk\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-8717","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/posts\/8717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/comments?post=8717"}],"version-history":[{"count":1,"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/posts\/8717\/revisions"}],"predecessor-version":[{"id":8720,"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/posts\/8717\/revisions\/8720"}],"wp:attachment":[{"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/media?parent=8717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/categories?post=8717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.punkgrossos.com\/index.php\/wp-json\/wp\/v2\/tags?post=8717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}